{"id":2096,"date":"2019-10-29T14:55:52","date_gmt":"2019-10-29T13:55:52","guid":{"rendered":"https:\/\/www.genaeclub.com\/bron\/?p=2096"},"modified":"2020-01-29T10:56:19","modified_gmt":"2020-01-29T09:56:19","slug":"hiver-on-se-renforce","status":"publish","type":"post","link":"https:\/\/www.genaeclub.com\/bron\/hiver-on-se-renforce\/","title":{"rendered":"L&rsquo;hiver, on se renforce ! Quelles pratiques choisir ?"},"content":{"rendered":"<h1 style=\"text-align: center;\">BRRR, l&rsquo;hiver on se renforce !<\/h1>\n<h2 style=\"text-align: center;\">Quelles pratiques choisir ?<\/h2>\n<p>Nos cours collectifs permettent \u00e0 la fois un renforcement complet mais surtout une tonification et un d\u00e9veloppement harmonieux.<\/p>\n<p><!--more--><br \/>\nDans chaque cours, nos coachs vous apporteront de nombreuses variations pour que ce cours soit accessible \u00e0 tous, selon son niveau ou son \u00e9tat de forme, tout en vous encourageant \u00e0 vous d\u00e9passer.<\/p>\n<p>Genae vous offre plus de 15 activit\u00e9s diff\u00e9rentes pour vous tonifier car l&rsquo;hiver, on  se renforce !<\/p>\n<h2>Mais alors, que choisir pour cet hiver ?<\/h2>\n<p>Vous avez les cours traditionnels comme le Cuisse Abdos Fessiers (pas besoin d\u2019un sch\u00e9ma), le Body Sculpt (avec petits halt\u00e8res et mix cardio-renfo) ou encore le circuit training (alternance d\u2019exercices cardio et renfo).<\/p>\n<p>Mais vous avez aussi des cours plus originaux comme le Natural Training (cours \u00e0 poids de corps de renforcement n\u00e9cessitant coordination et m\u00e9morisation), des cours de Trampo (super cardio coupl\u00e9 avec des exercices de renfo) ou le Challenge o\u00f9 vos coachs vous feront go\u00fbter \u00e0 toute leur cr\u00e9ativit\u00e9 \u00e0 travers des \u00ab menus du jour \u00bb.<\/p>\n<h2>L\u2019INFO EN + pour se renforcer en hiver ?<\/h2>\n<p>Avez-vous remarqu\u00e9 que, bien avant que cela soit tendance, Genae a toujours d\u00e9velopp\u00e9 des activit\u00e9s FONCTIONNELLES (voir prochainement l\u2019article de Vincent, manager sur Bron pour tout comprendre). Ce type d\u2019entra\u00eenement est tout simplement le plus proche de votre quotidien et un entra\u00eenement \u00ab utile \u00bb pour se renforcer.<\/p>\n<h2>GENAE C\u2019EST UN SPORT PLAISIR ET EFFICACE.<\/h2>\n<p>Alors faites vos choix et on se renforce !<\/p>\n<p>Pour plus de renseignement, RDV \u00e0 l&rsquo;accueil de votre salle de sport \u00e0 Bron.<\/p>\n<p>Pour acc\u00e9der facilement \u00e0 votre club de fitness \u00e0 Bron, <a href=\"https:\/\/www.genaeclub.com\/bron\/infos-pratiques\">retrouvez toutes <strong>nos coordonn\u00e9es ici.<\/strong><\/a><br \/>\nVous pouvez \u00e9galement <strong><a href=\"https:\/\/genae-bron.resamania.fr\/\">d\u00e9couvrir toutes nos offres sport plaisir ICI pour les membres du club !<\/a><\/strong><\/p>\n<p><a href=\"https:\/\/genae-bron.resamania.fr\/subscription\/\"><strong>Nouveau ?<\/strong> Faites votre inscription ici pour profiter du sport en illimit\u00e9 ou \u00e0 la s\u00e9ance !<\/a><\/p>\n<p>Genae est une salle de sport avec plus de 200 heures de cours vari\u00e9s par semaines.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BRRR, l&rsquo;hiver on se renforce ! Quelles pratiques choisir ? Nos cours collectifs permettent \u00e0 la fois un renforcement complet mais surtout une tonification et un d\u00e9veloppement harmonieux.<\/p>\n","protected":false},"author":2,"featured_media":2097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[21],"class_list":["post-2096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenement"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/posts\/2096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/comments?post=2096"}],"version-history":[{"count":0,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/posts\/2096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/media\/2097"}],"wp:attachment":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/media?parent=2096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/categories?post=2096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}