{"id":2393,"date":"2020-01-30T14:24:31","date_gmt":"2020-01-30T13:24:31","guid":{"rendered":"https:\/\/www.genaeclub.com\/bron\/?p=2393"},"modified":"2020-02-03T16:51:31","modified_gmt":"2020-02-03T15:51:31","slug":"la-semaine-du-velo","status":"publish","type":"post","link":"https:\/\/www.genaeclub.com\/bron\/la-semaine-du-velo\/","title":{"rendered":"La semaine du v\u00e9lo"},"content":{"rendered":"<p><strong>Le Peloton Velo<\/strong> revient pour une<strong> seconde \u00e9dition chez Genae<\/strong> \u00e0 partir du<strong> 10 F\u00e9vrier !<\/strong><\/p>\n<h2>Peloton Velo II, qu&rsquo;est-ce que c&rsquo;est ?<\/h2>\n<p>C&rsquo;est une semaine o\u00f9 <strong>les cours de v\u00e9lo sont mis \u00e0 l&rsquo;honneur !<\/strong><\/p>\n<p><!--more--><br \/>\nVenez vous challenger \u00e0 travers un <strong>championnat<\/strong> avec<strong> des points \u00e0 gagner<\/strong> lors de chaque cours et bien s\u00fbr <strong>des r\u00e9compenses<\/strong> pour les vainqueurs, <strong>des cours d\u00e9couvertes<\/strong> pour les novices dans cette activit\u00e9, des <strong>nouveaut\u00e9s<\/strong> avec le d\u00e9ploiement total de <strong>l&rsquo;application Motosumo<\/strong> qui permet de<strong> suivre en temps r\u00e9el ses performances<\/strong> lors de son cours et pas que&#8230;<br \/>\nDes <strong>cours \u00e0 th\u00e8mes<\/strong> selon les envies de vos coachs ainsi que des<strong> cours en team !<\/strong><\/p>\n<h2>Mais le V\u00e9lo chez Genae qu&rsquo;est-ce que c&rsquo;est ?<\/h2>\n<p>C&rsquo;est avant tout un cours <strong>cardio<\/strong>, <strong>ludique<\/strong>, en <strong>musique<\/strong> et <strong>animer par un coach !<\/strong><br \/>\nIl est <strong>accessible \u00e0 tous peu importe son niveau de pratique,<\/strong> du novice \u00e0 l&rsquo;expert.<br \/>\nCe cours image une sortie de v\u00e9lo que tout le monde peut faire, avec des passages :<\/p>\n<ul>\n<li>De<strong> vitesse p\u00e9dalage rapide,<\/strong> c&rsquo;est de la <strong>descente<\/strong> ou encore <strong>p\u00e9daler avec le vent dans le dos<\/strong>,<\/li>\n<li><strong>Vallonn\u00e9<\/strong> qui s&rsquo;apparente \u00e0 un<strong> faux plat,<\/strong> un p\u00e9dalage avec le<strong> vent de face<\/strong> cette fois-ci,<\/li>\n<li>De <strong>Force, \u00e7a grimpe,<\/strong> nous sommes en <strong>montagne<\/strong>.<\/li>\n<\/ul>\n<h2>Quels en sont les b\u00e9n\u00e9fices du v\u00e9lo ?<\/h2>\n<p>C&rsquo;est un cours <strong>engageant vos muscles<\/strong> ainsi que votre<strong> capacit\u00e9 cardio-vasculaire<\/strong>,<br \/>\nIl vous fera<strong> br\u00fbler un maximum de calories<\/strong> et <strong>tonifiera vos membres inf\u00e9rieurs,<\/strong><br \/>\nDe plus on notera un<strong> renforcement de la sangle abdominal.<\/strong><\/p>\n<h2>Pourquoi faire un cours de V\u00e9lo ?<\/h2>\n<p>Tout d&rsquo;abord car il est <strong>anim\u00e9 par un coach<\/strong> donc un travail en toute <strong>s\u00e9curit\u00e9<\/strong>,<br \/>\nIl est <strong>motivant<\/strong> de par <strong>la musique et l&rsquo;animation du coach,<\/strong><br \/>\nEt <strong>b\u00e9n\u00e9fique<\/strong> gr\u00e2ce \u00e0 ses <strong>vertus<\/strong> !<\/p>\n<p>En bref gr\u00e2ce \u00e0 ce cours<strong> vous d\u00e9penserez un maximum de calories<\/strong> tout en<strong> vous renfor\u00e7ant<\/strong> sans voir le temps passer, <strong>en toute s\u00e9curit\u00e9.<\/strong><\/p>\n<p>D\u00e9couvrez nos cours<strong><a href=\"https:\/\/www.genaeclub.com\/bron\/activite\/velo-25\/\"> V\u00e9lo 25&prime;<\/a>, <a href=\"https:\/\/www.genaeclub.com\/bron\/activite\/velo\/\">V\u00e9lo 50&prime;<\/a> et <a href=\"https:\/\/www.genaeclub.com\/bron\/activite\/velo-80\/\">V\u00e9lo 80&prime;<\/a> ! <\/strong><\/p>\n<p><a href=\"https:\/\/genae-bron.resamania.fr\/\"><strong>Tu es d\u00e9j\u00e0 membre du club ? <\/strong>Pour r\u00e9server, c&rsquo;est ICI !<\/a><br \/>\n<a href=\"https:\/\/genae-bron.resamania.fr\/subscription\/\"><strong>Nouveau ?<\/strong> Viens rejoindre la team en cliquant ici pour t&rsquo;inscrire.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Peloton Velo revient pour une seconde \u00e9dition chez Genae \u00e0 partir du 10 F\u00e9vrier ! Peloton Velo II, qu&rsquo;est-ce que c&rsquo;est ? C&rsquo;est une semaine o\u00f9 les cours de v\u00e9lo sont mis \u00e0 l&rsquo;honneur !<\/p>\n","protected":false},"author":2,"featured_media":2394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"class_list":["post-2393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/posts\/2393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/comments?post=2393"}],"version-history":[{"count":0,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/posts\/2393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/media\/2394"}],"wp:attachment":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/media?parent=2393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/categories?post=2393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}