{"id":9996,"date":"2021-11-10T14:31:25","date_gmt":"2021-11-10T13:31:25","guid":{"rendered":"https:\/\/www.genaeclub.com\/bron\/?p=9996"},"modified":"2021-11-10T14:45:52","modified_gmt":"2021-11-10T13:45:52","slug":"le-velo-quest-ce-que-cest","status":"publish","type":"post","link":"https:\/\/www.genaeclub.com\/bron\/le-velo-quest-ce-que-cest\/","title":{"rendered":"Le v\u00e9lo, qu&rsquo;est ce que c&rsquo;est ?"},"content":{"rendered":"<p>C&rsquo;est avant tout un cours cardio, ludique, en musique et animer par un coach !<br \/>\nIl est accessible \u00e0 tous peu importe son niveau de pratique, du novice \u00e0 l&rsquo;expert.<br \/>\nCe cours image une sortie de v\u00e9lo que l&rsquo;on peut tous faire, avec des passages :<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est avant tout un cours cardio, ludique, en musique et animer par un coach ! Il est accessible \u00e0 tous peu importe son niveau de pratique, du novice \u00e0 l&rsquo;expert. Ce cours image une sortie de v\u00e9lo que l&rsquo;on peut tous faire, avec des passages :<\/p>\n","protected":false},"author":2,"featured_media":10001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"class_list":["post-9996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/posts\/9996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/comments?post=9996"}],"version-history":[{"count":0,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/posts\/9996\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/media\/10001"}],"wp:attachment":[{"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/media?parent=9996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.genaeclub.com\/bron\/wp-json\/wp\/v2\/categories?post=9996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}